{"id":59135,"date":"2021-05-21T19:44:57","date_gmt":"2021-05-21T19:44:57","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/"},"modified":"2023-02-26T12:34:32","modified_gmt":"2023-02-26T12:34:32","slug":"lake-les-landes","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/","title":{"rendered":"Lake Les Landes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2944],"tags":[20405,20722,241,536,406,394,388,448,384,498,420,20889,590,45,421,502,401,494,395,78,423,504,577,30,416,492,23528,490,20372,23527,66,3136,497,244,23530,487,495,500,405,730,22152,20410,23531,22100,383,496,64,147,365,96,98,505,506,491,403,402,84,417,245,390,447,489,399,376,65,126,23529,391,493,486,21306,23532,302,1490,43],"type_de_logement":[],"activite":[],"class_list":["post-59135","hotel","type-hotel","status-publish","hentry","category-maison-de-vacances","tag-aeroport-de-bergerac-roumaniere","tag-aeroport-de-bordeaux-merignac","tag-aire-de-jeux-pour-enfants","tag-aire-de-pique-nique","tag-armoire-ou-penderie","tag-baignoire","tag-baignoire-ou-douche","tag-barbecue","tag-bouilloire-electrique","tag-bouilloire-ou-cafetiere","tag-canape","tag-cathedrale-saint-andre-de-bordeaux","tag-chaise-haute-pour-enfants","tag-chauffage","tag-cheminee","tag-coin-repas","tag-coin-salon","tag-cuisine","tag-douche","tag-enfants","tag-entree-privee","tag-espace-repas-exterieur","tag-etendoir","tag-extincteurs","tag-fer-a-repasser","tag-four","tag-golf-de-lande","tag-grille-pain","tag-hotel-france","tag-hotel-montpon-menesterol","tag-jardin","tag-jeux-de-societe-puzzles","tag-kitchenette","tag-lac","tag-lac-de-gurson-villefranch-de-lonchat","tag-lave-linge","tag-lave-vaisselle","tag-lecteur-cd","tag-linge-de-maison","tag-logement-entierement-situe-au-rez-de-chaussee","tag-maison-de-vacances-dordogne","tag-maison-de-vacances-france","tag-maison-de-vacances-montpon-menesterol","tag-maison-de-vacances-nouvelle-aquitaine","tag-materiel-de-repassage","tag-micro-ondes","tag-mobilier-exterieur","tag-non-fumeurs","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-securise","tag-patio","tag-piscine-privee","tag-plaque-de-cuisson","tag-portant","tag-prise-pres-du-lit","tag-reception-ouverte-24h-24","tag-refrigerateur","tag-riviere-ou-fleuve","tag-salle-de-bains-privative","tag-sol-carrele-ou-en-marbre","tag-table-a-manger","tag-television","tag-television-a-ecran-plat","tag-terrasse","tag-terrasse-bien-exposee","tag-the-river-isle-passes-through-montpon","tag-toilettes","tag-ustensiles-de-cuisine","tag-ventilateur","tag-ville-dordogne","tag-ville-montpon-menesterol","tag-ville-france","tag-ville-nouvelle-aquitaine","tag-wifi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lake Les Landes - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lake Les Landes - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T12:34:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/lake-les-landes\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/lake-les-landes\\\/\",\"name\":\"Lake Les Landes - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-21T19:44:57+00:00\",\"dateModified\":\"2023-02-26T12:34:32+00:00\",\"description\":\"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/lake-les-landes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/lake-les-landes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/lake-les-landes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lake Les Landes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lake Les Landes - H\u00f4tel 5 \u00c9toiles","description":"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/","og_locale":"es_ES","og_type":"article","og_title":"Lake Les Landes - H\u00f4tel 5 \u00c9toiles","og_description":"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T12:34:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/","name":"Lake Les Landes - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-21T19:44:57+00:00","dateModified":"2023-02-26T12:34:32+00:00","description":"Casa de vacaciones de lujo Lago Les Landesa Montpon-M\u00e9nest\u00e9rol (Dordo\u00f1a) descubra las mejores ofertas de este hotel franc\u00e9s de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/lake-les-landes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lake Les Landes"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/59135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=59135"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=59135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=59135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=59135"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=59135"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=59135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}