{"id":60168,"date":"2021-05-22T14:42:24","date_gmt":"2021-05-22T14:42:24","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/"},"modified":"2023-02-26T13:25:03","modified_gmt":"2023-02-26T13:25:03","slug":"royalton-bavaro-resort-spa-all-inclusive","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/","title":{"rendered":"Royalton Bavaro Resort &#038; Spa - All Inclusive"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2939],"tags":[26363,26362,241,102,150,42,37,59,270,124,85,196,154,79,44,859,35,26377,26375,26376,220,190,243,800,56,103,26366,26408,26403,26365,26360,26361,49,66,68,119,62,26364,580,365,38,26367,518,84,36,237,76,235,82,77,127,89,58,60,145,48,65,26373,2377,312,43],"type_de_logement":[],"activite":[],"class_list":["post-60168","hotel","type-hotel","status-publish","hentry","category-complexe-hotelier","tag-aeroport-international-casa-de-campo","tag-aeroport-international-de-punta-cana","tag-aire-de-jeux-pour-enfants","tag-anglais","tag-animations-en-soiree","tag-ascenseur","tag-bar","tag-blanchisserie-ou-laverie","tag-boutique-de-souvenirs-ou-cadeaux","tag-boutiques-dans-letablissement","tag-bureau-dexcursions","tag-centre-daffaires","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-complexe-hotelier-la-altagracia","tag-complexe-hotelier-punta-cana","tag-complexe-hotelier-republique-dominicaine","tag-court-de-tennis","tag-discotheque-ou-dj","tag-distributeur-automatique-de-billets-sur-place","tag-equipe-danimation","tag-espace-fumeurs","tag-espagnol","tag-golf-de-barcelo-bavaro","tag-golf-de-cana-bay","tag-golf-de-punta-blanca","tag-golf-et-country-club-cocotal","tag-hotel-punta-cana","tag-hotel-republique-dominicaine","tag-jacuzzi","tag-jardin","tag-massages","tag-menus-pour-regimes-speciaux-sur-demande","tag-nettoyage-a-sec","tag-palma-real-shopping-village","tag-parc-aquatique","tag-parking","tag-petit-dejeuner-en-chambre","tag-plaza-san-juan-shopping-center","tag-plongee-avec-tuba","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-jeux","tag-salles-de-reunions-ou-receptions","tag-salon-commun-ou-salle-de-television","tag-salon-daccueil-vip","tag-service-detage","tag-service-de-change","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-repassage","tag-snack-bar","tag-spa-et-centre-de-bien-etre","tag-terrasse","tag-ville-punta-cana","tag-ville-la-altagracia","tag-ville-republique-dominicaine","tag-wifi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Royalton Bavaro Resort &amp; Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Complejo hotelero de lujo Royalton Bavaro Resort &amp; Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Royalton Bavaro Resort &amp; Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Complejo hotelero de lujo Royalton Bavaro Resort &amp; Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T13:25:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/royalton-bavaro-resort-spa-all-inclusive\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/royalton-bavaro-resort-spa-all-inclusive\\\/\",\"name\":\"Royalton Bavaro Resort & Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-22T14:42:24+00:00\",\"dateModified\":\"2023-02-26T13:25:03+00:00\",\"description\":\"Complejo hotelero de lujo Royalton Bavaro Resort & Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/royalton-bavaro-resort-spa-all-inclusive\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/royalton-bavaro-resort-spa-all-inclusive\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/royalton-bavaro-resort-spa-all-inclusive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Royalton Bavaro Resort &#038; Spa - All Inclusive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Royalton Bavaro Resort & Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles","description":"Complejo hotelero de lujo Royalton Bavaro Resort & Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/","og_locale":"es_ES","og_type":"article","og_title":"Royalton Bavaro Resort & Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles","og_description":"Complejo hotelero de lujo Royalton Bavaro Resort & Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T13:25:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/","name":"Royalton Bavaro Resort & Spa - All Inclusive - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-22T14:42:24+00:00","dateModified":"2023-02-26T13:25:03+00:00","description":"Complejo hotelero de lujo Royalton Bavaro Resort & Spa - All Inclusivea Punta Cana (Hig\u00fcey) descubre las mejores ofertas de este 5 estrellas dominicano","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/royalton-bavaro-resort-spa-all-inclusive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Royalton Bavaro Resort &#038; Spa - All Inclusive"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/60168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=60168"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=60168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=60168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=60168"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=60168"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=60168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}