{"id":66754,"date":"2021-05-27T09:52:31","date_gmt":"2021-05-27T09:52:31","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/"},"modified":"2023-02-26T18:34:52","modified_gmt":"2023-02-26T18:34:52","slug":"doubletree-by-hilton-melaka","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/","title":{"rendered":"DoubleTree by Hilton Melaka"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[50824,50849,537,34,102,42,6387,87,51,37,59,121,143,31,32,7435,51135,196,51136,195,53,154,81,79,347,39,51133,44,859,35,33,261,90,56,30,75,67,40,153,50976,50967,50789,50977,63,206,7582,260,2910,6971,144,119,64,51189,62,147,365,96,130,98,38,46,51188,84,36,54,76,82,50,187,77,127,125,89,58,60,122,50973,51190,126,55,50979,50978,2054,2063,41,269],"type_de_logement":[5],"activite":[],"class_list":["post-66754","hotel","type-hotel","status-publish","hentry","category-hotel","tag-aeroport-international-de-kuala-lumpur","tag-aeroport-international-de-malacca","tag-aire-de-jeux-interieure","tag-alarme-de-securite","tag-anglais","tag-ascenseur","tag-baba-nyonya-heritage-museum","tag-bagagerie","tag-bain-a-vapeur","tag-bar","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-buffet-pour-enfants","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-centre-commercial-dataran-pahlawan-melaka-megamall","tag-centre-commercial-mahkota-parade","tag-centre-daffaires","tag-centre-medical-de-mahkota","tag-chaines-de-television-pour-enfants","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chinois","tag-chocolats-ou-biscuits","tag-christ-church-melaka","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-detecteurs-de-fumee","tag-dvd-ou-musique-pour-enfants","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-extincteurs","tag-fax-ou-photocopies","tag-fitness","tag-fruits","tag-garde-denfants","tag-hotel-etat-de-malacca","tag-hotel-malacca","tag-hotel-malaisie","tag-hotel-melaka","tag-insonorisation","tag-jeux-de-societe-ou-puzzles","tag-jonker-street","tag-livres","tag-malais","tag-menara-taming-sari","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-mobilier-exterieur","tag-mosquee-du-detroit-de-melaka","tag-nettoyage-a-sec","tag-non-fumeurs","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-interieur","tag-parking-securise","tag-petit-dejeuner-en-chambre","tag-piscine","tag-portuguese-square","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-repassage","tag-serviettes-de-piscine-ou-plage","tag-st-johns-fort","tag-temple-cheng-hoon-teng","tag-terrasse-bien-exposee","tag-vestiaires-salle-de-sport-spa","tag-ville-etat-de-malacca","tag-ville-malacca","tag-ville-malaisie","tag-ville-melaka","tag-vin-champagne","tag-wifi-en-supplement","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:34:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/doubletree-by-hilton-melaka\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/doubletree-by-hilton-melaka\\\/\",\"name\":\"DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-27T09:52:31+00:00\",\"dateModified\":\"2023-02-26T18:34:52+00:00\",\"description\":\"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/doubletree-by-hilton-melaka\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/doubletree-by-hilton-melaka\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/doubletree-by-hilton-melaka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DoubleTree by Hilton Melaka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles","description":"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/","og_locale":"es_ES","og_type":"article","og_title":"DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles","og_description":"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T18:34:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/","name":"DoubleTree by Hilton Melaka - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-27T09:52:31+00:00","dateModified":"2023-02-26T18:34:52+00:00","description":"DoubleTree by Hilton hotel de lujo Melakaa Malacca (Estado de Malacca) descubre las mejores ofertas de este 5 estrellas de Malasia","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/doubletree-by-hilton-melaka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"DoubleTree by Hilton Melaka"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/66754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=66754"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=66754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=66754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=66754"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=66754"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=66754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}