{"id":66775,"date":"2021-05-27T10:19:14","date_gmt":"2021-05-27T10:19:14","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/"},"modified":"2023-02-26T18:35:57","modified_gmt":"2023-02-26T18:35:57","slug":"fraser-residence-kuala-lumpur","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/","title":{"rendered":"Fraser Residence Kuala Lumpur"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[3843],"tags":[92,50824,50823,537,241,34,102,51028,51029,51030,51031,47248,406,392,42,87,394,51,12728,50876,419,366,59,384,121,400,85,31,32,420,50874,397,53,154,81,79,347,44,401,494,395,90,56,30,75,416,67,40,50869,50789,63,49,66,242,88,487,501,405,331,57,2910,50929,68,383,119,496,64,94,62,450,365,96,98,3131,50927,12328,46,491,61,84,417,36,390,237,54,76,50,187,77,89,58,430,60,408,386,122,145,47,48,12729,499,398,376,126,12329,391,91,50871,50928,493,55,50879,50880,50919,2054,41,43],"type_de_logement":[51032],"activite":[],"class_list":["post-66775","hotel","type-hotel","status-publish","hentry","category-apparthotel","tag-accessible-en-fauteuil-roulant","tag-aeroport-international-de-kuala-lumpur","tag-aeroport-sultan-abdul-aziz-shah-de-subang","tag-aire-de-jeux-interieure","tag-aire-de-jeux-pour-enfants","tag-alarme-de-securite","tag-anglais","tag-apparthotel-kuala-lumpur","tag-apparthotel-malaisie","tag-apparthotel-territoire-federal-de-kuala-lumpur","tag-apparthotel-wilayah-persekutuan-kuala-lumpur","tag-aquarium-aquaria-klcc","tag-armoire-ou-penderie","tag-articles-de-toilette-gratuits","tag-ascenseur","tag-bagagerie","tag-baignoire","tag-bain-a-vapeur","tag-bank-negara-malaysia-museum-and-art-gallery","tag-berjaya-times-square","tag-bidet","tag-billard","tag-blanchisserie-ou-laverie","tag-bouilloire-electrique","tag-bouteille-deau","tag-bureau","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-canape","tag-capital-square","tag-chaines-satellite","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chinois","tag-climatisation","tag-coin-salon","tag-cuisine","tag-douche","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-extincteurs","tag-fax-ou-photocopies","tag-fer-a-repasser","tag-fitness","tag-fruits","tag-hotel-kuala-lumpur","tag-hotel-malaisie","tag-insonorisation","tag-jacuzzi","tag-jardin","tag-jeux-de-plein-air-pour-enfants","tag-journaux","tag-lave-linge","tag-lecteur-dvd","tag-linge-de-maison","tag-livraison-de-courses","tag-location-de-voitures","tag-malais","tag-malaysian-philharmonic-orchestra","tag-massages","tag-materiel-de-repassage","tag-menus-pour-regimes-speciaux-sur-demande","tag-micro-ondes","tag-mobilier-exterieur","tag-navette-aeroport-en-supplement","tag-nettoyage-a-sec","tag-parcours-de-golf-a-moins-de-3-km","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-securise","tag-pavilion-kuala-lumpur","tag-petronas-philharmonic-hall-klcc","tag-petrosains","tag-piscine","tag-plaque-de-cuisson","tag-presse-a-pantalons","tag-reception-ouverte-24h-24","tag-refrigerateur","tag-restaurant","tag-salle-de-bains-privative","tag-salle-de-jeux","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-gratuit","tag-service-de-repassage","tag-service-de-reveil","tag-serviettes","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-spa","tag-spa-et-centre-de-bien-etre","tag-starhill-gallery","tag-station-daccueil-pour-ipod","tag-telephone","tag-television-a-ecran-plat","tag-terrasse-bien-exposee","tag-the-discovery-centre","tag-toilettes","tag-toilettes-avec-barres-dappui","tag-tour-kl","tag-tours-jumelles-petronas","tag-ustensiles-de-cuisine","tag-vestiaires-salle-de-sport-spa","tag-ville-kuala-lumpur","tag-ville-territoire-federal-de-kuala-lumpur","tag-ville-wilayah-persekutuan-kuala-lumpur","tag-ville-malaisie","tag-vin-champagne","tag-wifi","type_de_logement-apparthotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:35:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/fraser-residence-kuala-lumpur\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/fraser-residence-kuala-lumpur\\\/\",\"name\":\"Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-27T10:19:14+00:00\",\"dateModified\":\"2023-02-26T18:35:57+00:00\",\"description\":\"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/fraser-residence-kuala-lumpur\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/fraser-residence-kuala-lumpur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/fraser-residence-kuala-lumpur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fraser Residence Kuala Lumpur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles","description":"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/","og_locale":"es_ES","og_type":"article","og_title":"Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles","og_description":"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T18:35:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/","name":"Fraser Residence Kuala Lumpur - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-27T10:19:14+00:00","dateModified":"2023-02-26T18:35:57+00:00","description":"Fraser Residence Kuala Lumpura Luxury Aparthotel Kuala Lumpur (Territorio Federal de Kuala Lumpur) Descubra las mejores ofertas en este hotel de 5 estrellas de Malasia","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/fraser-residence-kuala-lumpur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Fraser Residence Kuala Lumpur"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/66775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=66775"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=66775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=66775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=66775"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=66775"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=66775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}