{"id":66776,"date":"2021-05-27T10:19:59","date_gmt":"2021-05-27T10:19:59","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/"},"modified":"2023-02-26T18:36:00","modified_gmt":"2023-02-26T18:36:00","slug":"furusato-midori-green-0515-tmn-mount-austin-jb","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/","title":{"rendered":"Furusato Midori Green 0515 @Tmn Mount Austin JB"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[578],"tags":[46371,46372,46373,241,102,188,50800,50798,50799,406,392,42,51,349,426,384,400,31,32,50797,50791,50840,347,44,502,494,653,395,78,577,416,67,50793,50794,50788,50789,66,50792,497,487,405,2910,496,64,147,385,50790,450,365,130,505,46,506,200,491,403,402,488,417,54,50,187,386,694,489,399,376,735,493,486,55,50801,2055,2054,43,50796],"type_de_logement":[50802],"activite":[],"class_list":["post-66776","hotel","type-hotel","status-publish","hentry","category-appartement","tag-aeroport-changi","tag-aeroport-de-batam-hang-nadim","tag-aeroport-international-de-senai","tag-aire-de-jeux-pour-enfants","tag-anglais","tag-animaux-de-compagnie","tag-appartement-johor","tag-appartement-johor-bahru","tag-appartement-malaisie","tag-armoire-ou-penderie","tag-articles-de-toilette-gratuits","tag-ascenseur","tag-bain-a-vapeur","tag-bain-en-plein-air","tag-balcon","tag-bouilloire-electrique","tag-bureau","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-centre-commercial-johor-premium-outlets","tag-centre-hospitalier-specialise-kpj-johor","tag-centre-hospitalier-specialise-kpj-puteri","tag-chinois","tag-climatisation","tag-coin-repas","tag-cuisine","tag-distributeur-automatique-de-boissons","tag-douche","tag-enfants","tag-etendoir","tag-fer-a-repasser","tag-fitness","tag-gare-routiere-de-larkin-sentral","tag-hopital-sultanah-aminah","tag-hotel-johor-bahru","tag-hotel-malaisie","tag-jardin","tag-kempas-medical-centre","tag-kitchenette","tag-lave-linge","tag-linge-de-maison","tag-malais","tag-micro-ondes","tag-mobilier-exterieur","tag-non-fumeurs","tag-papier-toilette","tag-parc-aquatique-austin-heights-water-adventure-park","tag-parcours-de-golf-a-moins-de-3-km","tag-parking","tag-parking-interieur","tag-patio","tag-piscine","tag-piscine-privee","tag-places-de-stationnement-dans-la-rue","tag-plaque-de-cuisson","tag-portant","tag-prise-pres-du-lit","tag-produits-menagers","tag-refrigerateur","tag-salle-de-sport","tag-sauna","tag-securite-24h-24","tag-serviettes","tag-serviettes-ou-linge-de-lit-avec-frais-supplementaires","tag-table-a-manger","tag-television","tag-television-a-ecran-plat","tag-tennis-de-table","tag-ustensiles-de-cuisine","tag-ventilateur","tag-vestiaires-salle-de-sport-spa","tag-ville-johor-bahru","tag-ville-johor","tag-ville-malaisie","tag-wifi","tag-zoo-de-singapour","type_de_logement-appartement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:36:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/furusato-midori-green-0515-tmn-mount-austin-jb\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/furusato-midori-green-0515-tmn-mount-austin-jb\\\/\",\"name\":\"Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-27T10:19:59+00:00\",\"dateModified\":\"2023-02-26T18:36:00+00:00\",\"description\":\"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/furusato-midori-green-0515-tmn-mount-austin-jb\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/furusato-midori-green-0515-tmn-mount-austin-jb\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/furusato-midori-green-0515-tmn-mount-austin-jb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Furusato Midori Green 0515 @Tmn Mount Austin JB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles","description":"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/","og_locale":"es_ES","og_type":"article","og_title":"Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles","og_description":"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T18:36:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/","name":"Furusato Midori Green 0515 @Tmn Mount Austin JB - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-27T10:19:59+00:00","dateModified":"2023-02-26T18:36:00+00:00","description":"Apartamento de lujo Furusato Midori Green 0515 @Tmn Mount Austin JBa Johor Bahru (Johor) descubre las mejores ofertas de este 5 estrellas de Malasia","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/furusato-midori-green-0515-tmn-mount-austin-jb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Furusato Midori Green 0515 @Tmn Mount Austin JB"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/66776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=66776"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=66776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=66776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=66776"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=66776"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=66776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}