{"id":66795,"date":"2021-05-27T10:32:18","date_gmt":"2021-05-27T10:32:18","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/"},"modified":"2023-02-26T18:36:56","modified_gmt":"2023-02-26T18:36:56","slug":"hatten-hotel-melaka","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/","title":{"rendered":"Hatten Hotel Melaka"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[50824,50849,102,42,87,37,59,124,7435,51135,196,51136,154,79,347,44,35,90,75,67,46114,50976,50967,50789,50977,7582,88,202,57,2910,253,191,192,193,68,6971,100,99,51189,50974,94,62,147,559,98,38,46,200,4423,84,36,245,54,76,82,50,187,77,89,58,430,60,51304,48,51307,6667,51305,51306,382,51190,55,50979,50978,2054,2063,43],"type_de_logement":[5],"activite":[],"class_list":["post-66795","hotel","type-hotel","status-publish","hentry","category-hotel","tag-aeroport-international-de-kuala-lumpur","tag-aeroport-international-de-malacca","tag-anglais","tag-ascenseur","tag-bagagerie","tag-bar","tag-blanchisserie-ou-laverie","tag-boutiques-dans-letablissement","tag-centre-commercial-dataran-pahlawan-melaka-megamall","tag-centre-commercial-mahkota-parade","tag-centre-daffaires","tag-centre-medical-de-mahkota","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-chinois","tag-climatisation","tag-coffre-fort","tag-equipements-pour-les-personnes-handicapees","tag-fax-ou-photocopies","tag-fitness","tag-forteresse-a-famosa","tag-hotel-etat-de-malacca","tag-hotel-malacca","tag-hotel-malaisie","tag-hotel-melaka","tag-jonker-street","tag-journaux","tag-location-de-velos","tag-location-de-voitures","tag-malais","tag-massage-corporel","tag-massage-des-pieds","tag-massage-du-cou","tag-massage-du-dos","tag-massages","tag-menara-taming-sari","tag-mer-ou-ocean","tag-montagne","tag-mosquee-du-detroit-de-melaka","tag-musee-straits-chinese-jewelry-museum-malacca","tag-navette-aeroport-en-supplement","tag-nettoyage-a-sec","tag-non-fumeurs","tag-parking-en-dehors-du-logement","tag-parking-securise","tag-petit-dejeuner-en-chambre","tag-piscine","tag-places-de-stationnement-dans-la-rue","tag-porta-de-santiago","tag-reception-ouverte-24h-24","tag-restaurant","tag-riviere-ou-fleuve","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-gratuit","tag-service-de-repassage","tag-sm-by-the-bay-amusement-park","tag-spa-et-centre-de-bien-etre","tag-st-johns-hill","tag-st-pauls-church","tag-straits-of-melaka","tag-sungai-melaka","tag-superette-sur-place","tag-temple-cheng-hoon-teng","tag-vestiaires-salle-de-sport-spa","tag-ville-etat-de-malacca","tag-ville-malacca","tag-ville-malaisie","tag-ville-melaka","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:36:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/hatten-hotel-melaka\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/hatten-hotel-melaka\\\/\",\"name\":\"Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-27T10:32:18+00:00\",\"dateModified\":\"2023-02-26T18:36:56+00:00\",\"description\":\"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/hatten-hotel-melaka\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/hatten-hotel-melaka\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/hatten-hotel-melaka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hatten Hotel Melaka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/","og_locale":"es_ES","og_type":"article","og_title":"Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T18:36:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/","name":"Hatten Hotel Melaka - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-27T10:32:18+00:00","dateModified":"2023-02-26T18:36:56+00:00","description":"Hotel de lujo Hatten Hotel Melakaa Malacca (Estado de Malaca) descubre las mejores ofertas de este 5 estrellas de Malasia","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/hatten-hotel-melaka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hatten Hotel Melaka"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/66795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=66795"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=66795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=66795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=66795"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=66795"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=66795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}