{"id":66902,"date":"2021-05-27T11:48:03","date_gmt":"2021-05-27T11:48:03","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/"},"modified":"2023-02-26T18:42:10","modified_gmt":"2023-02-26T18:42:10","slug":"pullman-kuching","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/","title":{"rendered":"Pullman Kuching"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[92,51319,34,102,150,42,87,51,336,37,51320,59,121,270,124,143,85,31,32,196,53,154,79,347,39,44,246,35,149,155,234,218,33,222,243,86,90,56,30,75,67,40,186,51318,50789,51325,5580,49,88,57,2910,68,144,119,100,64,62,147,236,96,199,130,38,61,84,36,245,54,76,82,51322,51324,50,187,77,127,125,89,58,430,60,122,145,50993,47,48,51321,51323,83,126,91,55,51326,2054,2067,41,43],"type_de_logement":[5],"activite":[],"class_list":["post-66902","hotel","type-hotel","status-publish","hentry","category-hotel","tag-accessible-en-fauteuil-roulant","tag-aeroport-international-de-kuching","tag-alarme-de-securite","tag-anglais","tag-animations-en-soiree","tag-ascenseur","tag-bagagerie","tag-bain-a-vapeur","tag-bain-de-pieds","tag-bar","tag-bazar-du-front-de-mer-de-kuching","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-boutique-de-souvenirs-ou-cadeaux","tag-boutiques-dans-letablissement","tag-buffet-pour-enfants","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-centre-daffaires","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-chinois","tag-chocolats-ou-biscuits","tag-climatisation","tag-coach-sportif-personnel","tag-coffre-fort","tag-concerts-ou-spectacles","tag-cordon-dalarme-dans-la-salle-de-bains","tag-cours-de-cuisine","tag-cours-de-yoga","tag-detecteurs-de-fumee","tag-diffusion-devenements-sportifs","tag-distributeur-automatique-de-billets-sur-place","tag-enregistrement-et-depart-prive","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-extincteurs","tag-fax-ou-photocopies","tag-fitness","tag-fruits","tag-galeries-dart-temporaires","tag-hotel-kuching","tag-hotel-malaisie","tag-hotel-sarawak","tag-indonesien","tag-jacuzzi","tag-journaux","tag-location-de-voitures","tag-malais","tag-massages","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-mer-ou-ocean","tag-mobilier-exterieur","tag-nettoyage-a-sec","tag-non-fumeurs","tag-parasols","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-avec-supplement","tag-parking-interieur","tag-petit-dejeuner-en-chambre","tag-presse-a-pantalons","tag-reception-ouverte-24h-24","tag-restaurant","tag-riviere-ou-fleuve","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sarawak-musuem","tag-sarawak-river","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-gratuit","tag-service-de-repassage","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-south-china-sea","tag-spa","tag-spa-et-centre-de-bien-etre","tag-st-thomass-cathedral","tag-stade-sarawak","tag-suite-nuptiale","tag-terrasse-bien-exposee","tag-toilettes-avec-barres-dappui","tag-vestiaires-salle-de-sport-spa","tag-ville-kuching","tag-ville-malaisie","tag-ville-sarawak","tag-vin-champagne","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pullman Kuching - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pullman Kuching - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T18:42:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/pullman-kuching\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/pullman-kuching\\\/\",\"name\":\"Pullman Kuching - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-27T11:48:03+00:00\",\"dateModified\":\"2023-02-26T18:42:10+00:00\",\"description\":\"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/pullman-kuching\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/pullman-kuching\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/pullman-kuching\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pullman Kuching\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pullman Kuching - H\u00f4tel 5 \u00c9toiles","description":"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/","og_locale":"es_ES","og_type":"article","og_title":"Pullman Kuching - H\u00f4tel 5 \u00c9toiles","og_description":"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T18:42:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/","name":"Pullman Kuching - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-27T11:48:03+00:00","dateModified":"2023-02-26T18:42:10+00:00","description":"Pullman luxury hotel Kuchinga Kuching (Sarawak) descubre las mejores ofertas de este 5 estrellas malayo","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/pullman-kuching\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pullman Kuching"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/66902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=66902"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=66902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=66902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=66902"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=66902"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=66902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}