{"id":68568,"date":"2021-05-28T14:18:24","date_gmt":"2021-05-28T14:18:24","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/"},"modified":"2023-02-26T20:03:22","modified_gmt":"2023-02-26T20:03:22","slug":"dolce-camporeal-lisboa","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/","title":{"rendered":"Dolce CampoReal Lisboa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2939],"tags":[92,57795,34,102,188,42,87,37,366,59,97,121,262,196,53,154,79,727,45,39,44,859,35,58045,57835,57836,58044,155,234,220,219,33,90,221,103,30,75,67,104,40,52,57743,58042,49,66,88,156,57,144,64,57800,99,728,147,236,450,365,130,46,200,132,363,84,36,237,54,76,82,50,58043,77,89,58,93,60,69,122,145,47,48,735,126,91,16598,57839,58046,2340,41,151,43],"type_de_logement":[51049],"activite":[],"class_list":["post-68568","hotel","type-hotel","status-publish","hentry","category-complexe-hotelier","tag-accessible-en-fauteuil-roulant","tag-aeroport-humberto-delgado","tag-alarme-de-securite","tag-anglais","tag-animaux-de-compagnie","tag-ascenseur","tag-bagagerie","tag-bar","tag-billard","tag-blanchisserie-ou-laverie","tag-borne-de-recharge-pour-les-vehicules-electriques","tag-bouteille-deau","tag-casiers","tag-centre-daffaires","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-chapelle","tag-chauffage","tag-chocolats-ou-biscuits","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-complexe-hotelier-lisbonne","tag-complexe-hotelier-portugal","tag-complexe-hotelier-region-centre","tag-complexe-hotelier-turcifal","tag-cordon-dalarme-dans-la-salle-de-bains","tag-cours-de-cuisine","tag-court-de-tennis","tag-cyclisme","tag-detecteurs-de-fumee","tag-equipements-pour-les-personnes-handicapees","tag-equitation","tag-espagnol","tag-extincteurs","tag-fax-ou-photocopies","tag-fitness","tag-francais","tag-fruits","tag-hammam","tag-hotel-portugal","tag-hotel-turcifal","tag-jacuzzi","tag-jardin","tag-journaux","tag-lavabo-bas-adapte-aux-personnes-a-mobilite-reduite","tag-location-de-voitures","tag-menus-enfants","tag-mobilier-exterieur","tag-monastere-des-hieronymites","tag-montagne","tag-mosquee-ou-lieu-de-culte","tag-non-fumeurs","tag-parasols","tag-parcours-de-golf-a-moins-de-3-km","tag-parking","tag-parking-interieur","tag-piscine","tag-places-de-stationnement-dans-la-rue","tag-portugais","tag-randonnee","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-jeux","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sauna","tag-serra-do-socorro","tag-service-detage","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-en-supplement","tag-service-de-repassage","tag-services-beaute","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-spa","tag-spa-et-centre-de-bien-etre","tag-tennis-de-table","tag-terrasse-bien-exposee","tag-toilettes-avec-barres-dappui","tag-ville-lisbonne","tag-ville-region-centre","tag-ville-turcifal","tag-ville-portugal","tag-vin-champagne","tag-visites-a-velo","tag-wifi","type_de_logement-complexe-hotelier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T20:03:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/dolce-camporeal-lisboa\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/dolce-camporeal-lisboa\\\/\",\"name\":\"Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-28T14:18:24+00:00\",\"dateModified\":\"2023-02-26T20:03:22+00:00\",\"description\":\"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/dolce-camporeal-lisboa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/dolce-camporeal-lisboa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/dolce-camporeal-lisboa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dolce CampoReal Lisboa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles","description":"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/","og_locale":"es_ES","og_type":"article","og_title":"Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles","og_description":"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T20:03:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/","name":"Dolce CampoReal Lisboa - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-28T14:18:24+00:00","dateModified":"2023-02-26T20:03:22+00:00","description":"Resort de lujo Dolce CampoReal Lisboaa Turcifal (Regi\u00f3n Centro) descubra las mejores ofertas de este 5 estrellas portugu\u00e9s","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/dolce-camporeal-lisboa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dolce CampoReal Lisboa"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/68568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=68568"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=68568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=68568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=68568"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=68568"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=68568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}