{"id":68699,"date":"2021-05-28T16:17:53","date_gmt":"2021-05-28T16:17:53","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/"},"modified":"2023-02-26T20:10:04","modified_gmt":"2023-02-26T20:10:04","slug":"santiago-de-alfama-boutique-hotel","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/","title":{"rendered":"Santiago de Alfama - Boutique Hotel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[92,57795,34,102,42,87,152,37,59,121,270,124,85,31,32,58093,80,81,79,42135,45,39,44,35,256,155,33,956,78,86,72,271,90,103,30,344,58095,75,104,40,189,153,73,355,16597,57743,57794,63,201,88,156,26122,57,240,259,253,255,254,191,192,193,194,68,144,119,51533,30932,64,94,198,197,275,62,147,148,96,129,130,98,239,38,58096,132,3721,61,84,36,133,76,235,82,58092,58094,187,77,125,89,58,60,69,145,71,238,70,48470,83,65,91,157,16598,57802,2340,41,203,151,43],"type_de_logement":[5],"activite":[],"class_list":["post-68699","hotel","type-hotel","status-publish","hentry","category-hotel","tag-accessible-en-fauteuil-roulant","tag-aeroport-humberto-delgado","tag-alarme-de-securite","tag-anglais","tag-ascenseur","tag-bagagerie","tag-balades-a-pied","tag-bar","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-boutique-de-souvenirs-ou-cadeaux","tag-boutiques-dans-letablissement","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-cathedrale-de-lisbonne","tag-chambres-anti-allergie","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chateau-de-saint-georges","tag-chauffage","tag-chocolats-ou-biscuits","tag-climatisation","tag-coffre-fort","tag-coiffure","tag-cordon-dalarme-dans-la-salle-de-bains","tag-detecteurs-de-fumee","tag-dona-maria-ii-national-theatre","tag-enfants","tag-enregistrement-et-depart-prive","tag-enveloppement-corporel","tag-epilation","tag-equipements-pour-les-personnes-handicapees","tag-espagnol","tag-extincteurs","tag-facture-fournie-sur-demande","tag-fado-museum","tag-fax-ou-photocopies","tag-francais","tag-fruits","tag-gamelles-pour-animaux-de-compagnie","tag-garde-denfants","tag-gommage-corporel","tag-hindi","tag-hotel-lisbonne","tag-hotel-portugal","tag-hotel-santa-maria-maior","tag-insonorisation","tag-italien","tag-journaux","tag-lavabo-bas-adapte-aux-personnes-a-mobilite-reduite","tag-letton","tag-location-de-voitures","tag-manucure","tag-maquillage","tag-massage-corporel","tag-massage-cranien","tag-massage-des-mains","tag-massage-des-pieds","tag-massage-du-cou","tag-massage-du-dos","tag-massage-en-couple","tag-massages","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-mercado-da-ribeira","tag-miradouro-da-senhora-do-monte","tag-mobilier-exterieur","tag-navette-aeroport-en-supplement","tag-navette-de-laeroport-a-letablissement","tag-navette-de-letablissement-a-laeroport","tag-neerlandais","tag-nettoyage-a-sec","tag-non-fumeurs","tag-panier-pour-animal-de-compagnie","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-en-dehors-du-logement-uniquement-sur-reservation-avec-supplement","tag-parking-interieur","tag-parking-securise","tag-pedicure","tag-petit-dejeuner-en-chambre","tag-portas-do-sol-belvedere","tag-portugais","tag-praca-do-comercio","tag-presse-a-pantalons","tag-reception-ouverte-24h-24","tag-restaurant","tag-russe","tag-salles-de-reunions-ou-receptions","tag-salon-commun-ou-salle-de-television","tag-salon-daccueil-vip","tag-santa-luzia-belvedere","tag-santiago-church","tag-securite-24h-24","tag-service-detage","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-repassage","tag-services-beaute","tag-snack-bar","tag-soins-corporels","tag-soins-des-cheveux","tag-soins-du-visage","tag-stade-de-luz","tag-suite-nuptiale","tag-terrasse","tag-toilettes-avec-barres-dappui","tag-toilettes-surelevees","tag-ville-lisbonne","tag-ville-santa-maria-maior","tag-ville-portugal","tag-vin-champagne","tag-visite-ou-cours-autour-de-la-culture-locale","tag-visites-a-velo","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T20:10:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/santiago-de-alfama-boutique-hotel\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/santiago-de-alfama-boutique-hotel\\\/\",\"name\":\"Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-28T16:17:53+00:00\",\"dateModified\":\"2023-02-26T20:10:04+00:00\",\"description\":\"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/santiago-de-alfama-boutique-hotel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/santiago-de-alfama-boutique-hotel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/santiago-de-alfama-boutique-hotel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santiago de Alfama - Boutique Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/","og_locale":"es_ES","og_type":"article","og_title":"Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T20:10:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/","name":"Santiago de Alfama - Boutique Hotel - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-28T16:17:53+00:00","dateModified":"2023-02-26T20:10:04+00:00","description":"Hotel de lujo Santiago de Alfama - Boutique Hotela Santa Maria Maior (Lisboa) descubre las mejores ofertas de este 5 estrellas portugu\u00e9s","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/santiago-de-alfama-boutique-hotel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Santiago de Alfama - Boutique Hotel"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/68699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=68699"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=68699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=68699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=68699"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=68699"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=68699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}