{"id":69769,"date":"2021-05-29T17:32:58","date_gmt":"2021-05-29T17:32:58","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/"},"modified":"2023-02-26T21:40:48","modified_gmt":"2023-02-26T21:40:48","slug":"rocky-ridge-cottage","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/","title":{"rendered":"Rocky Ridge Cottage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2944],"tags":[92,60669,536,406,392,394,388,349,426,448,384,498,400,420,195,397,590,154,79,45,421,340,44,502,401,594,494,33,395,78,423,90,56,504,577,30,344,416,492,503,490,60643,61219,63,66,206,497,487,495,500,405,730,60702,61942,60780,383,100,496,64,404,147,385,365,96,130,98,505,393,491,403,402,488,446,417,631,386,694,447,499,489,399,376,65,126,605,61940,493,486,61228,2213,2221,61941,43],"type_de_logement":[50907],"activite":[],"class_list":["post-69769","hotel","type-hotel","status-publish","hentry","category-maison-de-vacances","tag-accessible-en-fauteuil-roulant","tag-aeroport-de-nelson","tag-aire-de-pique-nique","tag-armoire-ou-penderie","tag-articles-de-toilette-gratuits","tag-baignoire","tag-baignoire-ou-douche","tag-bain-en-plein-air","tag-balcon","tag-barbecue","tag-bouilloire-electrique","tag-bouilloire-ou-cafetiere","tag-bureau","tag-canape","tag-chaines-de-television-pour-enfants","tag-chaines-satellite","tag-chaise-haute-pour-enfants","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-chauffage","tag-cheminee","tag-cheminee-exterieure","tag-climatisation","tag-coin-repas","tag-coin-salon","tag-couvertures-chauffantes","tag-cuisine","tag-detecteurs-de-fumee","tag-douche","tag-enfants","tag-entree-privee","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-espace-repas-exterieur","tag-etendoir","tag-extincteurs","tag-facture-fournie-sur-demande","tag-fer-a-repasser","tag-four","tag-grands-lits-de-2-metres-ou-plus","tag-grille-pain","tag-hotel-nouvelle-zelande","tag-hotel-takaka","tag-insonorisation","tag-jardin","tag-jeux-de-societe-ou-puzzles","tag-kitchenette","tag-lave-linge","tag-lave-vaisselle","tag-lecteur-cd","tag-linge-de-maison","tag-logement-entierement-situe-au-rez-de-chaussee","tag-maison-de-vacances-nouvelle-zelande","tag-maison-de-vacances-takaka","tag-maison-de-vacances-tasman","tag-materiel-de-repassage","tag-mer-ou-ocean","tag-micro-ondes","tag-mobilier-exterieur","tag-moquette","tag-non-fumeurs","tag-papier-toilette","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-interieur","tag-parking-securise","tag-patio","tag-peignoir","tag-plaque-de-cuisson","tag-portant","tag-prise-pres-du-lit","tag-produits-menagers","tag-radio","tag-refrigerateur","tag-reveil","tag-serviettes","tag-serviettes-ou-linge-de-lit-avec-frais-supplementaires","tag-sol-carrele-ou-en-marbre","tag-station-daccueil-pour-ipod","tag-table-a-manger","tag-television","tag-television-a-ecran-plat","tag-terrasse","tag-terrasse-bien-exposee","tag-toilettes-communes","tag-totoranui","tag-ustensiles-de-cuisine","tag-ventilateur","tag-ville-takaka","tag-ville-nouvelle-zelande","tag-ville-tasman","tag-wharariki-beach","tag-wifi","type_de_logement-maison-de-vacances"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T21:40:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/rocky-ridge-cottage\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/rocky-ridge-cottage\\\/\",\"name\":\"Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-29T17:32:58+00:00\",\"dateModified\":\"2023-02-26T21:40:48+00:00\",\"description\":\"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/rocky-ridge-cottage\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/rocky-ridge-cottage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/rocky-ridge-cottage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rocky Ridge Cottage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles","description":"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/","og_locale":"es_ES","og_type":"article","og_title":"Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles","og_description":"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T21:40:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/","name":"Rocky Ridge Cottage - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-29T17:32:58+00:00","dateModified":"2023-02-26T21:40:48+00:00","description":"Rocky Ridge Luxury Vacation Home Cottagea Takaka (Tasman) Descubra las mejores ofertas de 5 estrellas de Nueva Zelanda","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/rocky-ridge-cottage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Rocky Ridge Cottage"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/69769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=69769"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=69769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=69769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=69769"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=69769"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=69769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}