{"id":71601,"date":"2021-05-31T17:45:11","date_gmt":"2021-05-31T17:45:11","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/"},"modified":"2023-02-26T23:14:56","modified_gmt":"2023-02-26T23:14:56","slug":"holiday-home-mustikka","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/","title":{"rendered":"Holiday Home Mustikka"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2944],"tags":[65048,388,79,421,78,64866,65191,497,495,6970,65020,65044,65192,147,207,417,390,50,399,391,493,13652,65193,1665,1667,269],"type_de_logement":[50907],"activite":[],"class_list":["post-71601","hotel","type-hotel","status-publish","hentry","category-maison-de-vacances","tag-aeroport-de-kuopio","tag-baignoire-ou-douche","tag-chambres-non-fumeurs","tag-cheminee","tag-enfants","tag-hotel-finlande","tag-hotel-hakoniemi","tag-kitchenette","tag-lave-vaisselle","tag-maison-de-vacances-aucun-resultat-trouve","tag-maison-de-vacances-finlande","tag-maison-de-vacances-finlande-orientale","tag-maison-de-vacances-hakoniemi","tag-non-fumeurs","tag-parking-en-dehors-du-logement-avec-supplement","tag-refrigerateur","tag-salle-de-bains-privative","tag-sauna","tag-television","tag-toilettes","tag-ustensiles-de-cuisine","tag-ville-aucun-resultat-trouve","tag-ville-hakoniemi","tag-ville-finlande","tag-ville-finlande-orientale","tag-wifi-en-supplement","type_de_logement-maison-de-vacances"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T23:14:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/holiday-home-mustikka\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/holiday-home-mustikka\\\/\",\"name\":\"Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-31T17:45:11+00:00\",\"dateModified\":\"2023-02-26T23:14:56+00:00\",\"description\":\"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/holiday-home-mustikka\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/holiday-home-mustikka\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/holiday-home-mustikka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holiday Home Mustikka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles","description":"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/","og_locale":"es_ES","og_type":"article","og_title":"Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles","og_description":"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-26T23:14:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/","name":"Holiday Home Mustikka - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-31T17:45:11+00:00","dateModified":"2023-02-26T23:14:56+00:00","description":"Casa de vacaciones de lujo Holiday Home Mustikkaa Hakoniemi (Este de Finlandia) descubre las mejores ofertas en este hotel finland\u00e9s de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/holiday-home-mustikka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Holiday Home Mustikka"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/71601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=71601"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=71601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=71601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=71601"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=71601"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=71601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}