{"id":73408,"date":"2021-06-01T18:35:56","date_gmt":"2021-06-01T18:35:56","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/"},"modified":"2023-02-27T01:02:59","modified_gmt":"2023-02-27T01:02:59","slug":"solitaire-club-sky-bangkok","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/","title":{"rendered":"Solitaire Club Sky Bangkok"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[67584,67585,34,45964,102,150,52806,42,87,51,336,349,37,128,59,121,85,31,32,17949,196,195,53,80,154,81,79,39,44,149,33,190,86,56,30,75,67,26481,40,153,56880,68024,67674,67583,67594,67593,67569,63,88,253,255,254,191,192,193,194,68,144,64,94,198,197,62,147,236,10673,365,96,130,98,46,67592,84,36,54,76,235,82,56567,187,77,89,58,430,60,122,145,47,48,83,67677,55,67595,67596,2616,304,203,68023,43],"type_de_logement":[5],"activite":[],"class_list":["post-73408","hotel","type-hotel","status-publish","hentry","category-hotel","tag-aeroport-de-bangkok-suvarnabhumi","tag-aeroport-international-don-muang","tag-alarme-de-securite","tag-ambassade-de-suede","tag-anglais","tag-animations-en-soiree","tag-arab-street","tag-ascenseur","tag-bagagerie","tag-bain-a-vapeur","tag-bain-de-pieds","tag-bain-en-plein-air","tag-bar","tag-billets-pour-des-attractions-ou-spectacles","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-central-embassy","tag-centre-daffaires","tag-chaines-de-television-pour-enfants","tag-chaises-longues-ou-de-plage","tag-chambres-anti-allergie","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chocolats-ou-biscuits","tag-climatisation","tag-concerts-ou-spectacles","tag-detecteurs-de-fumee","tag-discotheque-ou-dj","tag-enregistrement-et-depart-prive","tag-espace-fumeurs","tag-extincteurs","tag-fax-ou-photocopies","tag-fitness","tag-fontaine-de-trevi","tag-fruits","tag-garde-denfants","tag-gaysorn-village-shopping-mall","tag-health-land-asoke","tag-hopital-international-bumrungrad","tag-hotel-bangkok","tag-hotel-krung-thep-maha-nakhon","tag-hotel-province-de-bangkok","tag-hotel-thailande","tag-insonorisation","tag-journaux","tag-massage-corporel","tag-massage-cranien","tag-massage-des-mains","tag-massage-des-pieds","tag-massage-du-cou","tag-massage-du-dos","tag-massage-en-couple","tag-massages","tag-menus-enfants","tag-mobilier-exterieur","tag-navette-aeroport-en-supplement","tag-navette-de-laeroport-a-letablissement","tag-navette-de-letablissement-a-laeroport","tag-nettoyage-a-sec","tag-non-fumeurs","tag-parasols","tag-parc-lumpini","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-interieur","tag-parking-securise","tag-piscine","tag-pratunam-market","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-commun-ou-salle-de-television","tag-salon-daccueil-vip","tag-sea-life-bangkok-ocean-world","tag-securite-24h-24","tag-service-detage","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-gratuit","tag-service-de-repassage","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-spa","tag-spa-et-centre-de-bien-etre","tag-suite-nuptiale","tag-sukhumvit-soi-11","tag-vestiaires-salle-de-sport-spa","tag-ville-bangkok","tag-ville-province-de-bangkok","tag-ville-krung-thep-maha-nakhon","tag-ville-thailande","tag-visite-ou-cours-autour-de-la-culture-locale","tag-wattana-church","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:02:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/solitaire-club-sky-bangkok\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/solitaire-club-sky-bangkok\\\/\",\"name\":\"Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-01T18:35:56+00:00\",\"dateModified\":\"2023-02-27T01:02:59+00:00\",\"description\":\"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/solitaire-club-sky-bangkok\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/solitaire-club-sky-bangkok\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/solitaire-club-sky-bangkok\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solitaire Club Sky Bangkok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/","og_locale":"es_ES","og_type":"article","og_title":"Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:02:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/","name":"Solitaire Club Sky Bangkok - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-01T18:35:56+00:00","dateModified":"2023-02-27T01:02:59+00:00","description":"Hotel de lujo Solitaire Club Sky Bangkoka Bangkok (Provincia de Bangkok) descubre las mejores ofertas de este 5 estrellas tailand\u00e9s","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/solitaire-club-sky-bangkok\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Solitaire Club Sky Bangkok"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73408"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73408"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73408"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}