{"id":73662,"date":"2021-06-01T22:08:27","date_gmt":"2021-06-01T22:08:27","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/"},"modified":"2023-02-27T01:15:35","modified_gmt":"2023-02-27T01:15:35","slug":"anantara-quy-nhon-villas","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/","title":{"rendered":"Anantara Quy Nhon Villas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[69336,69408,536,102,69410,51,336,349,152,37,123,366,59,121,124,85,196,53,79,39,44,859,246,35,234,218,67,104,69411,69407,69261,49,66,88,57,253,255,254,191,192,193,194,68,144,100,64,546,547,236,365,468,46,200,1009,538,518,69409,84,36,54,76,235,50,187,77,127,89,93,122,145,47,48,382,126,55,3985,69412,2771,2762,41,203,43],"type_de_logement":[5],"activite":[],"class_list":["post-73662","hotel","type-hotel","status-publish","hentry","category-hotel","tag-aeroport-de-dong-tac","tag-aeroport-de-phu-cat","tag-aire-de-pique-nique","tag-anglais","tag-bai-xep-beach","tag-bain-a-vapeur","tag-bain-de-pieds","tag-bain-en-plein-air","tag-balades-a-pied","tag-bar","tag-bibliotheque","tag-billard","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-boutiques-dans-letablissement","tag-bureau-dexcursions","tag-centre-daffaires","tag-chaises-longues-ou-de-plage","tag-chambres-non-fumeurs","tag-chocolats-ou-biscuits","tag-climatisation","tag-club-pour-enfants","tag-coach-sportif-personnel","tag-coffre-fort","tag-cours-de-cuisine","tag-cours-de-yoga","tag-fitness","tag-francais","tag-hotel-binh-dinh","tag-hotel-quy-nhon","tag-hotel-vietnam","tag-jacuzzi","tag-jardin","tag-journaux","tag-location-de-voitures","tag-massage-corporel","tag-massage-cranien","tag-massage-des-mains","tag-massage-des-pieds","tag-massage-du-cou","tag-massage-du-dos","tag-massage-en-couple","tag-massages","tag-menus-enfants","tag-mer-ou-ocean","tag-mobilier-exterieur","tag-nage","tag-nourriture-et-boissons","tag-parasols","tag-parking","tag-peche","tag-piscine","tag-places-de-stationnement-dans-la-rue","tag-plage-privee","tag-plages","tag-plongee-avec-tuba","tag-quy-nhon","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-commun-ou-salle-de-television","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-concierge","tag-service-de-navette-en-supplement","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-spa","tag-spa-et-centre-de-bien-etre","tag-superette-sur-place","tag-terrasse-bien-exposee","tag-vestiaires-salle-de-sport-spa","tag-vietnamien","tag-ville-quy-nhon","tag-ville-binh-dinh","tag-ville-vietnam","tag-vin-champagne","tag-visite-ou-cours-autour-de-la-culture-locale","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:15:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/anantara-quy-nhon-villas\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/anantara-quy-nhon-villas\\\/\",\"name\":\"Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-01T22:08:27+00:00\",\"dateModified\":\"2023-02-27T01:15:35+00:00\",\"description\":\"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/anantara-quy-nhon-villas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/anantara-quy-nhon-villas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/anantara-quy-nhon-villas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anantara Quy Nhon Villas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/","og_locale":"es_ES","og_type":"article","og_title":"Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:15:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/","name":"Anantara Quy Nhon Villas - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-01T22:08:27+00:00","dateModified":"2023-02-27T01:15:35+00:00","description":"Hotel de lujo Anantara Quy Nhon Villasa Quy Nh\u01a1n (Binh Dinh) descubre las mejores ofertas de este vietnamita de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/anantara-quy-nhon-villas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Anantara Quy Nhon Villas"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73662"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73662"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73662"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}