{"id":73701,"date":"2021-06-01T22:46:29","date_gmt":"2021-06-01T22:46:29","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/"},"modified":"2023-02-27T01:17:35","modified_gmt":"2023-02-27T01:17:35","slug":"d1mension-residences","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/","title":{"rendered":"D1Mension Residences"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[3843],"tags":[69353,69600,69603,69604,69457,392,69599,69537,400,10645,154,79,44,494,69595,78,344,69352,69261,497,487,405,20885,69597,48533,385,69601,95,46,69602,386,122,376,69598,69596,69366,69539,2762,43],"type_de_logement":[51032],"activite":[],"class_list":["post-73701","hotel","type-hotel","status-publish","hentry","category-apparthotel","tag-aeroport-international-de-tan-son-nhat","tag-an-dong-plaza","tag-apparthotel-ho-chi-minh-ville","tag-apparthotel-thanh-pho-ho-chi-minh","tag-apparthotel-vietnam","tag-articles-de-toilette-gratuits","tag-artinus-3d-art-museum","tag-ben-thanh-street-food-market","tag-bureau","tag-centre-commercial-takashimaya-vietnam","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-climatisation","tag-cuisine","tag-eglise-cho-quan","tag-enfants","tag-facture-fournie-sur-demande","tag-hotel-ho-chi-minh-ville","tag-hotel-vietnam","tag-kitchenette","tag-lave-linge","tag-linge-de-maison","tag-musee-des-beaux-arts","tag-nowzone-fashion-mall","tag-palais-de-la-reunification","tag-papier-toilette","tag-parc-tao-dan","tag-parking-uniquement-sur-reservation-avec-supplement","tag-piscine","tag-quai-nha-rong","tag-serviettes","tag-serviettes-de-piscine-ou-plage","tag-television-a-ecran-plat","tag-thai-binh-market","tag-universite-des-sciences-de-ho-chi-minh-ville","tag-ville-ho-chi-minh-ville","tag-ville-thanh-pho-ho-chi-minh","tag-ville-vietnam","tag-wifi","type_de_logement-apparthotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D1Mension Residences - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D1Mension Residences - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:17:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/d1mension-residences\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/d1mension-residences\\\/\",\"name\":\"D1Mension Residences - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-01T22:46:29+00:00\",\"dateModified\":\"2023-02-27T01:17:35+00:00\",\"description\":\"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/d1mension-residences\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/d1mension-residences\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/d1mension-residences\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D1Mension Residences\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D1Mension Residences - H\u00f4tel 5 \u00c9toiles","description":"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/","og_locale":"es_ES","og_type":"article","og_title":"D1Mension Residences - H\u00f4tel 5 \u00c9toiles","og_description":"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:17:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/","name":"D1Mension Residences - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-01T22:46:29+00:00","dateModified":"2023-02-27T01:17:35+00:00","description":"Aparthotel de lujo D1Mension Residencesa Ciudad Ho Chi Minh (Qu\u1eadn 1) descubre las mejores ofertas en este 5 estrellas vietnamita","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/d1mension-residences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"D1Mension Residences"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73701"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73701"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73701"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}