{"id":73708,"date":"2021-06-01T22:53:28","date_gmt":"2021-06-01T22:53:28","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/"},"modified":"2023-02-27T01:17:57","modified_gmt":"2023-02-27T01:17:57","slug":"diamond-westlake-suites","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/","title":{"rendered":"Diamond Westlake Suites"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[466],"tags":[92,69277,69439,537,241,34,102,69632,69631,69630,69530,406,392,42,87,394,388,51,448,593,419,366,59,97,384,121,124,143,400,85,31,32,420,69629,196,2808,195,396,397,53,154,81,79,45,389,421,340,44,859,35,517,502,401,220,494,120,33,243,395,261,78,86,423,271,90,56,409,30,344,75,416,67,186,153,73,490,26793,69522,69438,69261,63,66,242,497,244,69627,487,501,405,331,260,57,69628,240,69445,3499,383,144,119,496,795,64,404,424,94,198,197,62,385,236,69623,450,365,96,130,98,239,69626,46,491,403,61,402,488,69624,84,64301,417,36,631,245,390,237,54,76,235,50,444,187,77,127,125,89,58,430,60,408,69,386,122,694,145,71,70,47,526,499,382,489,398,399,376,5677,735,126,41601,391,69625,493,55,3396,3985,69449,69448,2772,2762,41,36337,43],"type_de_logement":[50847],"activite":[],"class_list":["post-73708","hotel","type-hotel","status-publish","hentry","category-appartements","tag-accessible-en-fauteuil-roulant","tag-aeroport-international-de-cat-bi","tag-aeroport-international-de-noi-bai","tag-aire-de-jeux-interieure","tag-aire-de-jeux-pour-enfants","tag-alarme-de-securite","tag-anglais","tag-appartements-ha-noi","tag-appartements-ha-noi-municipality","tag-appartements-hanoi","tag-appartements-vietnam","tag-armoire-ou-penderie","tag-articles-de-toilette-gratuits","tag-ascenseur","tag-bagagerie","tag-baignoire","tag-baignoire-ou-douche","tag-bain-a-vapeur","tag-barbecue","tag-barrieres-de-securite-pour-bebes","tag-bidet","tag-billard","tag-blanchisserie-ou-laverie","tag-borne-de-recharge-pour-les-vehicules-electriques","tag-bouilloire-electrique","tag-bouteille-deau","tag-boutiques-dans-letablissement","tag-buffet-pour-enfants","tag-bureau","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-canape","tag-centre-commercial-vincom-center-nguyen-chi-thanh","tag-centre-daffaires","tag-chaines-a-la-carte","tag-chaines-de-television-pour-enfants","tag-chaines-du-cable","tag-chaines-satellite","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chauffage","tag-chaussons","tag-cheminee","tag-cheminee-exterieure","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-coffre-fort-pour-ordinateur-portable","tag-coin-repas","tag-coin-salon","tag-court-de-tennis","tag-cuisine","tag-dejeuner-a-emporter","tag-detecteurs-de-fumee","tag-distributeur-automatique-de-billets-sur-place","tag-douche","tag-dvd-ou-musique-pour-enfants","tag-enfants","tag-enregistrement-et-depart-prive","tag-entree-privee","tag-epilation","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-etages-superieurs-accessibles-par-ascenseur","tag-extincteurs","tag-facture-fournie-sur-demande","tag-fax-ou-photocopies","tag-fer-a-repasser","tag-fitness","tag-galeries-dart-temporaires","tag-garde-denfants","tag-gommage-corporel","tag-grille-pain","tag-hanoi-old-city-gate","tag-hoan-kiem-lake","tag-hotel-hanoi","tag-hotel-vietnam","tag-insonorisation","tag-jardin","tag-jeux-de-plein-air-pour-enfants","tag-kitchenette","tag-lac","tag-lac-de-louest","tag-lave-linge","tag-lecteur-dvd","tag-linge-de-maison","tag-livraison-de-courses","tag-livres","tag-location-de-voitures","tag-machinco-building-mdri","tag-manucure","tag-marche-de-dong-xuan","tag-materiel-de-badminton","tag-materiel-de-repassage","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-micro-ondes","tag-minigolf","tag-mobilier-exterieur","tag-moquette","tag-moustiquaire","tag-navette-aeroport-en-supplement","tag-navette-de-laeroport-a-letablissement","tag-navette-de-letablissement-a-laeroport","tag-nettoyage-a-sec","tag-papier-toilette","tag-parasols","tag-parc-aquatique-west-lake-park","tag-parcours-de-golf-a-moins-de-3-km","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-interieur","tag-parking-securise","tag-pedicure","tag-phu-tay-ho","tag-piscine","tag-plaque-de-cuisson","tag-portant","tag-presse-a-pantalons","tag-prise-pres-du-lit","tag-produits-menagers","tag-quang-ba-flower-market","tag-reception-ouverte-24h-24","tag-red-river","tag-refrigerateur","tag-restaurant","tag-reveil","tag-riviere-ou-fleuve","tag-salle-de-bains-privative","tag-salle-de-jeux","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-commun-ou-salle-de-television","tag-sauna","tag-seche-linge","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-gratuit","tag-service-de-repassage","tag-service-de-reveil","tag-services-beaute","tag-serviettes","tag-serviettes-de-piscine-ou-plage","tag-serviettes-ou-linge-de-lit-avec-frais-supplementaires","tag-snack-bar","tag-soins-corporels","tag-soins-du-visage","tag-spa","tag-squash","tag-station-daccueil-pour-ipod","tag-superette-sur-place","tag-table-a-manger","tag-telephone","tag-television","tag-television-a-ecran-plat","tag-temple-de-la-litterature-de-hanoi","tag-tennis-de-table","tag-terrasse-bien-exposee","tag-the-scientific-center","tag-toilettes","tag-trinh-cong-son-walking-street","tag-ustensiles-de-cuisine","tag-vestiaires-salle-de-sport-spa","tag-vietnam-museum-of-ethnology","tag-vietnamien","tag-ville-ha-noi-municipality","tag-ville-hanoi","tag-ville-ha-noi","tag-ville-vietnam","tag-vin-champagne","tag-west-lake","tag-wifi","type_de_logement-appartements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:17:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/diamond-westlake-suites\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/diamond-westlake-suites\\\/\",\"name\":\"Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-01T22:53:28+00:00\",\"dateModified\":\"2023-02-27T01:17:57+00:00\",\"description\":\"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/diamond-westlake-suites\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/diamond-westlake-suites\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/diamond-westlake-suites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diamond Westlake Suites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles","description":"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/","og_locale":"es_ES","og_type":"article","og_title":"Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles","og_description":"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:17:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/","name":"Diamond Westlake Suites - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-01T22:53:28+00:00","dateModified":"2023-02-27T01:17:57+00:00","description":"Apartamentos de lujo Diamond Westlake Suitesa Hanoi (T\u00e2y H\u1ed3) descubre las mejores ofertas de este vietnamita de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/diamond-westlake-suites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Diamond Westlake Suites"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73708"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73708"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73708"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}