{"id":73896,"date":"2021-06-02T06:08:46","date_gmt":"2021-06-02T06:08:46","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/"},"modified":"2023-02-27T01:27:30","modified_gmt":"2023-02-27T01:27:30","slug":"potique-hotel","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/","title":{"rendered":"Potique Hotel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[92,69308,69336,241,34,69342,102,42,69452,87,152,37,59,121,270,85,196,154,79,39,44,859,246,35,155,33,86,90,30,75,67,40,40113,69517,69335,69261,156,69344,69455,62,69318,147,236,96,2815,46,69317,84,36,17647,35763,54,76,50,187,77,127,125,89,58,93,60,122,145,47,48,65,157,45318,55,3985,69346,2766,2762,41,43,69453],"type_de_logement":[5],"activite":[],"class_list":["post-73896","hotel","type-hotel","status-publish","hentry","category-hotel","tag-accessible-en-fauteuil-roulant","tag-aeroport-de-cam-ranh","tag-aeroport-de-dong-tac","tag-aire-de-jeux-pour-enfants","tag-alarme-de-securite","tag-alexandre-yersin-museum","tag-anglais","tag-ascenseur","tag-bac-thanh-church","tag-bagagerie","tag-balades-a-pied","tag-bar","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-boutique-de-souvenirs-ou-cadeaux","tag-bureau-dexcursions","tag-centre-daffaires","tag-chambres-familiales","tag-chambres-non-fumeurs","tag-chocolats-ou-biscuits","tag-climatisation","tag-club-pour-enfants","tag-coach-sportif-personnel","tag-coffre-fort","tag-cordon-dalarme-dans-la-salle-de-bains","tag-detecteurs-de-fumee","tag-enregistrement-et-depart-prive","tag-equipements-pour-les-personnes-handicapees","tag-extincteurs","tag-fax-ou-photocopies","tag-fitness","tag-fruits","tag-gare-de-nha-trang","tag-hotel-khanh-hoa","tag-hotel-nha-trang","tag-hotel-vietnam","tag-lavabo-bas-adapte-aux-personnes-a-mobilite-reduite","tag-long-son-pagoda","tag-marche-de-dam","tag-nettoyage-a-sec","tag-nha-trang-catheral","tag-non-fumeurs","tag-parasols","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-en-dehors-du-logement-uniquement-sur-reservation","tag-piscine","tag-place-2-4-square","tag-reception-ouverte-24h-24","tag-restaurant","tag-sailing-center-vietnam","tag-sailing-club","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-en-supplement","tag-service-de-repassage","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-spa","tag-spa-et-centre-de-bien-etre","tag-terrasse","tag-toilettes-surelevees","tag-tram-huong-tower","tag-vestiaires-salle-de-sport-spa","tag-vietnamien","tag-ville-nha-trang","tag-ville-khanh-hoa","tag-ville-vietnam","tag-vin-champagne","tag-wifi","tag-xom-moi-market","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Potique Hotel - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Potique Hotel - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:27:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/potique-hotel\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/potique-hotel\\\/\",\"name\":\"Potique Hotel - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-02T06:08:46+00:00\",\"dateModified\":\"2023-02-27T01:27:30+00:00\",\"description\":\"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/potique-hotel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/potique-hotel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/potique-hotel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Potique Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Potique Hotel - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/","og_locale":"es_ES","og_type":"article","og_title":"Potique Hotel - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:27:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/","name":"Potique Hotel - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-02T06:08:46+00:00","dateModified":"2023-02-27T01:27:30+00:00","description":"Hotel de lujo Potique Hotela Nha Trang (Khanh Hoa) descubre las mejores ofertas de este vietnamita de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/potique-hotel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Potique Hotel"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73896"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73896"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73896"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}