{"id":73925,"date":"2021-06-02T06:33:07","date_gmt":"2021-06-02T06:33:07","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/"},"modified":"2023-02-27T01:28:57","modified_gmt":"2023-02-27T01:28:57","slug":"salinda-resort-phu-quoc-island","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/","title":{"rendered":"Salinda Resort Phu Quoc Island"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2939],"tags":[92,625,17717,17716,346,537,34,102,150,42,87,336,37,366,128,59,270,124,143,31,32,26266,262,196,195,53,80,154,81,79,39,44,859,35,69500,69507,69508,69509,69273,149,548,234,219,33,70022,320,69915,261,86,90,56,103,30,75,104,186,153,355,69497,69261,63,201,66,244,260,923,48558,69501,68,144,119,64,99,546,198,197,62,147,547,236,69656,96,2815,98,38,69499,46,1009,538,61,69498,84,36,133,76,82,50,187,77,127,125,89,58,60,122,223,47,48,69655,83,69554,126,157,26234,55,3985,69557,69510,69511,2774,2762,203,43],"type_de_logement":[51049],"activite":[],"class_list":["post-73925","hotel","type-hotel","status-publish","hentry","category-complexe-hotelier","tag-accessible-en-fauteuil-roulant","tag-activites-nautiques","tag-aeroport-international-de-phu-quoc","tag-aeroport-international-de-sihanoukville","tag-aides-visuelles-braille","tag-aire-de-jeux-interieure","tag-alarme-de-securite","tag-anglais","tag-animations-en-soiree","tag-ascenseur","tag-bagagerie","tag-bain-de-pieds","tag-bar","tag-billard","tag-billets-pour-des-attractions-ou-spectacles","tag-blanchisserie-ou-laverie","tag-boutique-de-souvenirs-ou-cadeaux","tag-boutiques-dans-letablissement","tag-buffet-pour-enfants","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-cascade-de-suoi-tranh","tag-casiers","tag-centre-daffaires","tag-chaines-de-television-pour-enfants","tag-chaises-longues-ou-de-plage","tag-chambres-anti-allergie","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chocolats-ou-biscuits","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-coi-nguon-museum","tag-complexe-hotelier-phu-quoc","tag-complexe-hotelier-phu-quoc-island","tag-complexe-hotelier-tinh-kien-giang","tag-complexe-hotelier-vietnam","tag-concerts-ou-spectacles","tag-coucher-de-soleil","tag-cours-de-cuisine","tag-cyclisme","tag-detecteurs-de-fumee","tag-dien-tien","tag-diners-a-theme","tag-duong-dong","tag-dvd-ou-musique-pour-enfants","tag-enregistrement-et-depart-prive","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-espagnol","tag-extincteurs","tag-fax-ou-photocopies","tag-francais","tag-galeries-dart-temporaires","tag-garde-denfants","tag-hindi","tag-hotel-phu-quoc","tag-hotel-vietnam","tag-insonorisation","tag-italien","tag-jardin","tag-lac","tag-livres","tag-long-beach","tag-long-beach-centre","tag-marche-nocturne-de-phu-quoc","tag-massages","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-mobilier-exterieur","tag-montagne","tag-nage","tag-navette-de-laeroport-a-letablissement","tag-navette-de-letablissement-a-laeroport","tag-nettoyage-a-sec","tag-non-fumeurs","tag-nourriture-et-boissons","tag-parasols","tag-parc-safari-vinpearl-safari-phu-quoc","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-en-dehors-du-logement-uniquement-sur-reservation","tag-parking-securise","tag-petit-dejeuner-en-chambre","tag-phu-quoc-pearl-farm","tag-piscine","tag-plage-privee","tag-plages","tag-presse-a-pantalons","tag-prison-de-phu-quoc","tag-reception-ouverte-24h-24","tag-restaurant","tag-russe","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sauna","tag-securite-24h-24","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-repassage","tag-serviettes-de-piscine-ou-plage","tag-soirees-film","tag-spa","tag-spa-et-centre-de-bien-etre","tag-su-muon-pagoda","tag-suite-nuptiale","tag-sung-hung-pagoda","tag-terrasse-bien-exposee","tag-toilettes-surelevees","tag-tranh-waterfall","tag-vestiaires-salle-de-sport-spa","tag-vietnamien","tag-village-de-pecheurs-ham-ninh","tag-ville-phu-quoc","tag-ville-phu-quoc-island","tag-ville-tinh-kien-giang","tag-ville-vietnam","tag-visite-ou-cours-autour-de-la-culture-locale","tag-wifi","type_de_logement-complexe-hotelier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:28:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/salinda-resort-phu-quoc-island\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/salinda-resort-phu-quoc-island\\\/\",\"name\":\"Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-02T06:33:07+00:00\",\"dateModified\":\"2023-02-27T01:28:57+00:00\",\"description\":\"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/salinda-resort-phu-quoc-island\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/salinda-resort-phu-quoc-island\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/salinda-resort-phu-quoc-island\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salinda Resort Phu Quoc Island\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles","description":"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/","og_locale":"es_ES","og_type":"article","og_title":"Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles","og_description":"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:28:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/","name":"Salinda Resort Phu Quoc Island - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-02T06:33:07+00:00","dateModified":"2023-02-27T01:28:57+00:00","description":"Resort de lujo Salinda Resort Phu Quoc Islanda Phu Quoc (Isla de Phu Quoc) descubre las mejores ofertas de este vietnamita de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/salinda-resort-phu-quoc-island\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Salinda Resort Phu Quoc Island"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73925"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73925"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73925"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}