{"id":73966,"date":"2021-06-02T07:04:28","date_gmt":"2021-06-02T07:04:28","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/"},"modified":"2023-02-27T01:31:03","modified_gmt":"2023-02-27T01:31:03","slug":"sun-spa-resort-villa","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/","title":{"rendered":"Sun Spa Resort &#038; Villa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2939],"tags":[332,69717,241,102,150,87,51,37,123,366,59,97,121,270,124,85,469,262,196,195,53,81,79,727,44,859,35,256,257,69722,69723,69273,149,258,218,220,219,120,190,243,86,271,800,90,56,344,75,67,153,73,52,69716,69261,63,579,66,242,88,202,57,240,68,3499,119,795,728,94,62,69721,147,236,365,98,468,239,38,46,1009,538,471,61,84,36,237,54,76,82,50,77,127,125,89,93,60,69,122,145,71,238,70,47,48,735,126,55,3985,69724,2783,2762,43],"type_de_logement":[51049],"activite":[],"class_list":["post-73966","hotel","type-hotel","status-publish","hentry","category-complexe-hotelier","tag-aerobic","tag-aeroport-de-dong-hoi","tag-aire-de-jeux-pour-enfants","tag-anglais","tag-animations-en-soiree","tag-bagagerie","tag-bain-a-vapeur","tag-bar","tag-bibliotheque","tag-billard","tag-blanchisserie-ou-laverie","tag-borne-de-recharge-pour-les-vehicules-electriques","tag-bouteille-deau","tag-boutique-de-souvenirs-ou-cadeaux","tag-boutiques-dans-letablissement","tag-bureau-dexcursions","tag-canoe-kayak","tag-casiers","tag-centre-daffaires","tag-chaines-de-television-pour-enfants","tag-chaises-longues-ou-de-plage","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chapelle","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-coiffure","tag-coloration","tag-complexe-hotelier-dong-hoi","tag-complexe-hotelier-quang-binh","tag-complexe-hotelier-vietnam","tag-concerts-ou-spectacles","tag-coupe-de-cheveux","tag-cours-de-yoga","tag-court-de-tennis","tag-cyclisme","tag-dejeuner-a-emporter","tag-discotheque-ou-dj","tag-distributeur-automatique-de-billets-sur-place","tag-enregistrement-et-depart-prive","tag-epilation","tag-equipe-danimation","tag-equipements-pour-les-personnes-handicapees","tag-espace-fumeurs","tag-facture-fournie-sur-demande","tag-fax-ou-photocopies","tag-fitness","tag-garde-denfants","tag-gommage-corporel","tag-hammam","tag-hotel-dong-hoi","tag-hotel-vietnam","tag-insonorisation","tag-installations-de-sports-nautiques-sur-place","tag-jardin","tag-jeux-de-plein-air-pour-enfants","tag-journaux","tag-location-de-velos","tag-location-de-voitures","tag-manucure","tag-massages","tag-materiel-de-badminton","tag-menus-pour-regimes-speciaux-sur-demande","tag-minigolf","tag-mosquee-ou-lieu-de-culte","tag-navette-aeroport-en-supplement","tag-nettoyage-a-sec","tag-nhat-le-beach","tag-non-fumeurs","tag-parasols","tag-parking","tag-parking-securise","tag-peche","tag-pedicure","tag-petit-dejeuner-en-chambre","tag-piscine","tag-plage-privee","tag-plages","tag-planche-a-voile","tag-presse-a-pantalons","tag-reception-ouverte-24h-24","tag-restaurant","tag-salle-de-jeux","tag-salle-de-sport","tag-salles-de-reunions-ou-receptions","tag-salon-daccueil-vip","tag-sauna","tag-service-detage","tag-service-de-change","tag-service-de-cireur","tag-service-de-concierge","tag-service-de-navette-en-supplement","tag-service-de-repassage","tag-services-beaute","tag-serviettes-de-piscine-ou-plage","tag-snack-bar","tag-soins-corporels","tag-soins-des-cheveux","tag-soins-du-visage","tag-spa","tag-spa-et-centre-de-bien-etre","tag-tennis-de-table","tag-terrasse-bien-exposee","tag-vestiaires-salle-de-sport-spa","tag-vietnamien","tag-ville-dong-hoi","tag-ville-quang-binh","tag-ville-vietnam","tag-wifi","type_de_logement-complexe-hotelier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sun Spa Resort &amp; Villa - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Resort de lujo Sun Spa Resort &amp; Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sun Spa Resort &amp; Villa - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Resort de lujo Sun Spa Resort &amp; Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:31:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/sun-spa-resort-villa\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/sun-spa-resort-villa\\\/\",\"name\":\"Sun Spa Resort & Villa - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-02T07:04:28+00:00\",\"dateModified\":\"2023-02-27T01:31:03+00:00\",\"description\":\"Resort de lujo Sun Spa Resort & Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/sun-spa-resort-villa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/sun-spa-resort-villa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/sun-spa-resort-villa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sun Spa Resort &#038; Villa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sun Spa Resort & Villa - H\u00f4tel 5 \u00c9toiles","description":"Resort de lujo Sun Spa Resort & Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/","og_locale":"es_ES","og_type":"article","og_title":"Sun Spa Resort & Villa - H\u00f4tel 5 \u00c9toiles","og_description":"Resort de lujo Sun Spa Resort & Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:31:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/","name":"Sun Spa Resort & Villa - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-02T07:04:28+00:00","dateModified":"2023-02-27T01:31:03+00:00","description":"Resort de lujo Sun Spa Resort & Villaa Dong Hoi (Quang Binh) descubre las mejores ofertas de este vietnamita de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/sun-spa-resort-villa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sun Spa Resort &#038; Villa"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/73966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=73966"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=73966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=73966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=73966"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=73966"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=73966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}