{"id":74531,"date":"2021-06-02T15:46:33","date_gmt":"2021-06-02T15:46:33","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/"},"modified":"2023-02-27T01:58:55","modified_gmt":"2023-02-27T01:58:55","slug":"mount-xanadu-resorts","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/","title":{"rendered":"Mount Xanadu Resorts"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2939],"tags":[70407,70406,537,241,536,71927,71933,102,87,152,366,59,121,85,195,53,154,81,79,39,44,859,35,71940,70402,70163,70403,320,71938,56,67,40,71932,71923,355,71930,70150,63,71939,66,242,88,71935,71931,244,57,253,255,254,191,192,193,68,3499,144,119,100,64,99,94,198,197,71934,236,365,96,98,468,38,71937,363,84,36,245,237,54,235,77,89,58,93,122,47,48,83,735,126,796,71941,70187,1793,1796,71936,43],"type_de_logement":[51049],"activite":[],"class_list":["post-74531","hotel","type-hotel","status-publish","hentry","category-complexe-hotelier","tag-aeroport-international-de-calicut","tag-aeroport-international-de-cannanore","tag-aire-de-jeux-interieure","tag-aire-de-jeux-pour-enfants","tag-aire-de-pique-nique","tag-ambukuthi-mala","tag-ancient-jain-temple","tag-anglais","tag-bagagerie","tag-balades-a-pied","tag-billard","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-bureau-dexcursions","tag-chaines-de-television-pour-enfants","tag-chaises-longues-ou-de-plage","tag-chambres-familiales","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chocolats-ou-biscuits","tag-climatisation","tag-club-pour-enfants","tag-coffre-fort","tag-complexe-hotelier-ambalavayal","tag-complexe-hotelier-etat-du-kerala","tag-complexe-hotelier-inde","tag-complexe-hotelier-kerala","tag-diners-a-theme","tag-edakkal-cave","tag-espace-fumeurs","tag-fitness","tag-fruits","tag-grottes-dedakkal","tag-heritage-museum","tag-hindi","tag-hotel-ambalavayal","tag-hotel-inde","tag-insonorisation","tag-jain-temple-sulthan-battery","tag-jardin","tag-jeux-de-plein-air-pour-enfants","tag-journaux","tag-kanthanpara-waterfalls","tag-karapuzha-dam","tag-lac","tag-location-de-voitures","tag-massage-corporel","tag-massage-cranien","tag-massage-des-mains","tag-massage-des-pieds","tag-massage-du-cou","tag-massage-du-dos","tag-massages","tag-materiel-de-badminton","tag-menus-enfants","tag-menus-pour-regimes-speciaux-sur-demande","tag-mer-ou-ocean","tag-mobilier-exterieur","tag-montagne","tag-navette-aeroport-en-supplement","tag-navette-de-laeroport-a-letablissement","tag-navette-de-letablissement-a-laeroport","tag-neelimala-viewpoint","tag-parasols","tag-parking","tag-parking-accessible-aux-personnes-a-mobilite-reduite","tag-parking-securise","tag-peche","tag-petit-dejeuner-en-chambre","tag-phantom-rock","tag-randonnee","tag-reception-ouverte-24h-24","tag-restaurant","tag-riviere-ou-fleuve","tag-salle-de-jeux","tag-salle-de-sport","tag-salon-commun-ou-salle-de-television","tag-service-detage","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-navette-en-supplement","tag-serviettes-de-piscine-ou-plage","tag-spa","tag-spa-et-centre-de-bien-etre","tag-suite-nuptiale","tag-tennis-de-table","tag-terrasse-bien-exposee","tag-tir-a-larc","tag-ville-ambalavayal","tag-ville-etat-du-kerala","tag-ville-inde","tag-ville-kerala","tag-wayanad-heritage-museum","tag-wifi","type_de_logement-complexe-hotelier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T01:58:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mount-xanadu-resorts\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mount-xanadu-resorts\\\/\",\"name\":\"Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-02T15:46:33+00:00\",\"dateModified\":\"2023-02-27T01:58:55+00:00\",\"description\":\"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mount-xanadu-resorts\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mount-xanadu-resorts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mount-xanadu-resorts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mount Xanadu Resorts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles","description":"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/","og_locale":"es_ES","og_type":"article","og_title":"Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles","og_description":"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T01:58:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/","name":"Mount Xanadu Resorts - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-02T15:46:33+00:00","dateModified":"2023-02-27T01:58:55+00:00","description":"Mount Xanadu Resortsa Ambalavayal (Wayanad) resort de lujo descubra las mejores ofertas en este hotel indio de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mount-xanadu-resorts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mount Xanadu Resorts"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/74531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=74531"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=74531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=74531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=74531"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=74531"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=74531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}