{"id":75837,"date":"2021-06-03T15:15:59","date_gmt":"2021-06-03T15:15:59","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/"},"modified":"2023-02-27T03:02:26","modified_gmt":"2023-02-27T03:02:26","slug":"ennios-boutique-hotel","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/","title":{"rendered":"Ennios Boutique Hotel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[2],"tags":[72620,72621,72619,34,102,87,37,72628,59,121,54671,85,31,32,80,81,79,45,44,35,33,86,56,30,75,40,158,72626,47201,74672,72602,72618,63,201,88,75170,73233,73232,144,64,62,282,147,98,95,276,61,74,36,82,127,89,58,60,145,72627,13283,83,64323,75169,72634,72633,2425,2424,41,75168,43],"type_de_logement":[5],"activite":[],"class_list":["post-75837","hotel","type-hotel","status-publish","hentry","category-hotel","tag-aeroport-de-bournemouth","tag-aeroport-de-londres-gatwick","tag-aeroport-de-southampton","tag-alarme-de-securite","tag-anglais","tag-bagagerie","tag-bar","tag-beaulieu","tag-blanchisserie-ou-laverie","tag-bouteille-deau","tag-bucklers-hard","tag-bureau-dexcursions","tag-cameras-de-surveillance-a-lexterieur","tag-cameras-de-surveillance-dans-les-parties-communes","tag-chambres-anti-allergie","tag-chambres-insonorisees","tag-chambres-non-fumeurs","tag-chauffage","tag-climatisation","tag-coffre-fort","tag-detecteurs-de-fumee","tag-enregistrement-et-depart-prive","tag-espace-fumeurs","tag-extincteurs","tag-fax-ou-photocopies","tag-fruits","tag-grec","tag-holy-rood-church","tag-hotel-angleterre","tag-hotel-hampshire","tag-hotel-royaume-uni","tag-hotel-southampton","tag-insonorisation","tag-italien","tag-journaux","tag-mayflower-park","tag-mayflower-theatre","tag-medieval-merchants-house","tag-menus-enfants","tag-mobilier-exterieur","tag-nettoyage-a-sec","tag-non","tag-non-fumeurs","tag-parking-securise","tag-parking-uniquement-sur-reservation-avec-supplement","tag-polonais","tag-presse-a-pantalons","tag-reserve-aux-adultes","tag-restaurant","tag-salon-daccueil-vip","tag-service-de-change","tag-service-de-concierge","tag-service-de-menage-quotidien","tag-service-de-repassage","tag-snack-bar","tag-southampton-guildhall","tag-st-michaels-church","tag-suite-nuptiale","tag-terrain-de-cricket-ageas-bowl","tag-tudor-house-museum","tag-ville-hampshire","tag-ville-southampton","tag-ville-angleterre","tag-ville-royaume-uni","tag-vin-champagne","tag-westgate","tag-wifi","type_de_logement-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T03:02:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/ennios-boutique-hotel\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/ennios-boutique-hotel\\\/\",\"name\":\"Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-03T15:15:59+00:00\",\"dateModified\":\"2023-02-27T03:02:26+00:00\",\"description\":\"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/ennios-boutique-hotel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/ennios-boutique-hotel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/ennios-boutique-hotel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ennios Boutique Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles","description":"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/","og_locale":"es_ES","og_type":"article","og_title":"Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles","og_description":"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T03:02:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/","name":"Ennios Boutique Hotel - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-03T15:15:59+00:00","dateModified":"2023-02-27T03:02:26+00:00","description":"Hotel de lujo Ennios Boutique Hotela Southampton (Southampton) descubre las mejores ofertas en este hotel brit\u00e1nico de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/ennios-boutique-hotel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ennios Boutique Hotel"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/75837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=75837"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=75837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=75837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=75837"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=75837"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=75837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}