{"id":78641,"date":"2021-06-05T14:02:28","date_gmt":"2021-06-05T14:02:28","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/"},"modified":"2023-02-27T07:39:24","modified_gmt":"2023-02-27T07:39:24","slug":"mr-lu-s-guesthouse","status":"publish","type":"hotel","link":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/","title":{"rendered":"Mr Lu's Guesthouse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"categories":[433],"tags":[19523,19524,102,188,20350,426,19778,384,154,347,19961,78,19533,19772,19476,19522,66,20142,79949,78008,19774,19775,207,84,77,376,65,32803,19541,1310,1314,407,19532,19777,19776,2822],"type_de_logement":[51023],"activite":[],"class_list":["post-78641","hotel","type-hotel","status-publish","hentry","category-maison-dhotes","tag-aeroport-de-lijiang-sanyi","tag-aeroport-de-ninglang-luguhu","tag-anglais","tag-animaux-de-compagnie","tag-baisui-bridge","tag-balcon","tag-black-dragon-pond-park","tag-bouilloire-electrique","tag-chambres-familiales","tag-chinois","tag-dongba-culture-museum","tag-enfants","tag-fang-guoyus-former-residence","tag-guan-men-kou","tag-hotel-chine","tag-hotel-lijiang","tag-jardin","tag-maison-dhotes-chine","tag-maison-dhotes-lijiang","tag-maison-dhotes-yunnan","tag-mufu-palace","tag-nanmen-bridge","tag-parking-en-dehors-du-logement-avec-supplement","tag-reception-ouverte-24h-24","tag-service-detage","tag-television-a-ecran-plat","tag-terrasse","tag-theatre-national-croate-ivan-pl-zajc","tag-ville-lijiang","tag-ville-chine","tag-ville-yunnan","tag-vue","tag-wangu-pavilion","tag-water-wheels","tag-white-horse-dragon-pond-temple","tag-zhongyi-market","type_de_logement-maison-dhotes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mr Lu&#039;s Guesthouse - H\u00f4tel 5 \u00c9toiles<\/title>\n<meta name=\"description\" content=\"Casa de hu\u00e9spedes de lujo Mr Lu&#039;s Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mr Lu&#039;s Guesthouse - H\u00f4tel 5 \u00c9toiles\" \/>\n<meta property=\"og:description\" content=\"Casa de hu\u00e9spedes de lujo Mr Lu&#039;s Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T07:39:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mr-lu-s-guesthouse\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mr-lu-s-guesthouse\\\/\",\"name\":\"Mr Lu's Guesthouse - H\u00f4tel 5 \u00c9toiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-05T14:02:28+00:00\",\"dateModified\":\"2023-02-27T07:39:24+00:00\",\"description\":\"Casa de hu\u00e9spedes de lujo Mr Lu's Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mr-lu-s-guesthouse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mr-lu-s-guesthouse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/hotel\\\/mr-lu-s-guesthouse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mr Lu's Guesthouse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mr Lu's Guesthouse - H\u00f4tel 5 \u00c9toiles","description":"Casa de hu\u00e9spedes de lujo Mr Lu's Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/","og_locale":"es_ES","og_type":"article","og_title":"Mr Lu's Guesthouse - H\u00f4tel 5 \u00c9toiles","og_description":"Casa de hu\u00e9spedes de lujo Mr Lu's Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas","og_url":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-27T07:39:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/","url":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/","name":"Mr Lu's Guesthouse - H\u00f4tel 5 \u00c9toiles","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-06-05T14:02:28+00:00","dateModified":"2023-02-27T07:39:24+00:00","description":"Casa de hu\u00e9spedes de lujo Mr Lu's Guesthousea Lijiang (Yunnan) descubre las mejores ofertas de este chino de 5 estrellas","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/hotel\/mr-lu-s-guesthouse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mr Lu's Guesthouse"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel\/78641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=78641"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=78641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=78641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=78641"},{"taxonomy":"type_de_logement","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/type_de_logement?post=78641"},{"taxonomy":"activite","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/activite?post=78641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}