{"id":34963,"date":"2021-07-04T02:19:38","date_gmt":"2021-05-13T21:06:06","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/"},"modified":"2023-02-22T11:15:35","modified_gmt":"2023-02-22T11:15:35","slug":"taiba","status":"publish","type":"page","link":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/","title":{"rendered":"Ta\u00edba"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":33464,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[283],"tags":[1100,1218,1226],"class_list":["post-34963","page","type-page","status-publish","hentry","category-ville","tag-ville-amerique","tag-ville-bresil","tag-ville-ceara"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o<\/title>\n<meta name=\"description\" content=\"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T11:15:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/taiba\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/taiba\\\/\",\"name\":\"Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-13T21:06:06+00:00\",\"dateModified\":\"2023-02-22T11:15:35+00:00\",\"description\":\"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/taiba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/taiba\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/taiba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/bresil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ta\u00edba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o","description":"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/","og_locale":"es_ES","og_type":"article","og_title":"Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o","og_description":"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","og_url":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-22T11:15:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/","url":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/","name":"Los mejores hoteles 5 estrellas en Ta\u00edba Hotel de lujo brasile\u00f1o","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-13T21:06:06+00:00","dateModified":"2023-02-22T11:15:35+00:00","description":"Descubre los mejores hoteles de 5 estrellas Ta\u00edba Hoteles de lujo en Ta\u00edba con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/bresil\/taiba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Brasil","item":"https:\/\/hotel5etoiles.com\/es\/bresil\/"},{"@type":"ListItem","position":3,"name":"Ta\u00edba"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/34963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=34963"}],"version-history":[{"count":1,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/34963\/revisions"}],"predecessor-version":[{"id":81009,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/34963\/revisions\/81009"}],"up":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/33464"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=34963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=34963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=34963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}