{"id":41357,"date":"2021-07-04T01:47:56","date_gmt":"2021-05-14T01:12:46","guid":{"rendered":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/"},"modified":"2023-02-22T13:51:41","modified_gmt":"2023-02-22T13:51:41","slug":"kocaeli","status":"publish","type":"page","link":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/","title":{"rendered":"Kocaeli"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":33778,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[283],"tags":[63623,285,2718,2692],"class_list":["post-41357","page","type-page","status-publish","hentry","category-ville","tag-ville-region-de-marmara","tag-ville-asie","tag-ville-kocaeli","tag-ville-turquie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco<\/title>\n<meta name=\"description\" content=\"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco\" \/>\n<meta property=\"og:description\" content=\"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel 5 Estrellas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T13:51:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/kocaeli\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/kocaeli\\\/\",\"name\":\"Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-14T01:12:46+00:00\",\"dateModified\":\"2023-02-22T13:51:41+00:00\",\"description\":\"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/kocaeli\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/kocaeli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/kocaeli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pavo\",\"item\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/turquie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kocaeli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"name\":\"Hotel 5 Estrellas\",\"description\":\"Los mejores hoteles de 5 estrellas del mundo reunidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#organization\",\"name\":\"H\u00f4tel 5 \u00c9toiles\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"contentUrl\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/05\\\/Logo-hotel-luxe-transparent-bleu-jaune.png\",\"width\":700,\"height\":110,\"caption\":\"H\u00f4tel 5 \u00c9toiles\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel5etoiles.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco","description":"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/","og_locale":"es_ES","og_type":"article","og_title":"Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco","og_description":"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","og_url":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/","og_site_name":"Hotel 5 Estrellas","article_modified_time":"2023-02-22T13:51:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/","url":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/","name":"Los mejores hoteles 5 estrellas en Kocaeli Hotel de lujo turco","isPartOf":{"@id":"https:\/\/hotel5etoiles.com\/es\/#website"},"datePublished":"2021-05-14T01:12:46+00:00","dateModified":"2023-02-22T13:51:41+00:00","description":"Descubre los mejores hoteles de 5 estrellas Kocaeli Hoteles de lujo en Kocaeli con servicios hoteleros de calidad. Reserve el hotel de 5 estrellas de sus sue\u00f1os para su estancia.","breadcrumb":{"@id":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel5etoiles.com\/es\/turquie\/kocaeli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hotel5etoiles.com\/es\/"},{"@type":"ListItem","position":2,"name":"pavo","item":"https:\/\/hotel5etoiles.com\/es\/turquie\/"},{"@type":"ListItem","position":3,"name":"Kocaeli"}]},{"@type":"WebSite","@id":"https:\/\/hotel5etoiles.com\/es\/#website","url":"https:\/\/hotel5etoiles.com\/es\/","name":"Hotel 5 Estrellas","description":"Los mejores hoteles de 5 estrellas del mundo reunidos","publisher":{"@id":"https:\/\/hotel5etoiles.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel5etoiles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hotel5etoiles.com\/es\/#organization","name":"H\u00f4tel 5 \u00c9toiles","url":"https:\/\/hotel5etoiles.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","contentUrl":"https:\/\/hotel5etoiles.com\/es\/wp-content\/uploads\/sites\/3\/2021\/05\/Logo-hotel-luxe-transparent-bleu-jaune.png","width":700,"height":110,"caption":"H\u00f4tel 5 \u00c9toiles"},"image":{"@id":"https:\/\/hotel5etoiles.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/41357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/comments?post=41357"}],"version-history":[{"count":1,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/41357\/revisions"}],"predecessor-version":[{"id":87399,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/41357\/revisions\/87399"}],"up":[{"embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/pages\/33778"}],"wp:attachment":[{"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/media?parent=41357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/categories?post=41357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel5etoiles.com\/es\/wp-json\/wp\/v2\/tags?post=41357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}